{"id":29299,"date":"2022-04-22T07:11:20","date_gmt":"2022-04-22T05:11:20","guid":{"rendered":"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?p=29299"},"modified":"2022-04-22T07:11:22","modified_gmt":"2022-04-22T05:11:22","slug":"nachhaltiges-reisen","status":"publish","type":"post","link":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/nachhaltiges-reisen\/","title":{"rendered":"Nachhaltig Reisen &#8211;  9 einfache Tipps f\u00fcr mehr \u00d6kotourismus"},"content":{"rendered":"\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-1d92c5e5\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<p class=\"wp-block-paragraph\">Reisen macht gl\u00fccklich, entspannt und erweitert den Horizont! Allerdings belastet der Tourismus auch zunehmend die Natur und gilt als Beschleuniger des Klimawandels: Regenw\u00e4lder werden r\u00fccksichtslos abgeholzt, Weltmeere \u00fcberfischt und verschmutzt und vor allem Flugreisen sind einer der gr\u00f6\u00dften Klimas\u00fcnder. Egal, wo wir uns auch auf der Welt befinden, der Klimawandel macht uns \u00fcberall zu schaffen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Dies soll jetzt aber nicht gleich hei\u00dfen, dass wir g\u00e4nzlich auf unseren Traumurlaub verzichten m\u00fcssen. Dennoch stellt sich die Frage, wie sich<strong> Reisen und Umweltschutz gut miteinander verbinden<\/strong> lassen. Und tats\u00e4chlich k\u00f6nnen wir schon mit kleinen \u00c4nderungen unserer bisherigen Urlaubsgewohnheiten und ein bisschen Achtsamkeit einen gro\u00dfen Unterschied machen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wir geben euch einen ersten \u00dcberblick \u00fcber das Thema \u201eNachhaltig Reisen\u201c und zeigen euch 9 einfache Tipps und Tricks, mit denen ihr euren Urlaub nachhaltiger gestalten k\u00f6nnt. Denn schon mit kleinen Dingen k\u00f6nnen wir alle daf\u00fcr sorgen, dass die Welt ein bisschen gr\u00fcner bleibt.<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-334e4470\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\t\t\t\t<div class=\"wp-block-uagb-table-of-contents uagb-toc__align-left uagb-toc__columns-2  uagb-block-5f0e3026      \"\n\t\t\t\t\tdata-scroll= \"1\"\n\t\t\t\t\tdata-offset= \"30\"\n\t\t\t\t\tstyle=\"\"\n\t\t\t\t>\n\t\t\t\t<div class=\"uagb-toc__wrap\">\n\t\t\t\t\t\t<div class=\"uagb-toc__title\">\n\t\t\t\t\t\t\tInhaltsverzeichnis\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"uagb-toc__list-wrap \">\n\t\t\t\t\t\t<ol class=\"uagb-toc__list\"><li class=\"uagb-toc__list\"><a href=\"#was-ist-\u00f6kotourismus-\u00fcberhaupt\" class=\"uagb-toc-link__trigger\">Was ist \u00d6kotourismus \u00fcberhaupt?<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-1-w\u00e4hlt-ein-reiseziel-in-der-n\u00e4he\" class=\"uagb-toc-link__trigger\">Tipp 1: W\u00e4hlt ein Reiseziel in der N\u00e4he<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-2-verzichtet-aufs-fliegen\" class=\"uagb-toc-link__trigger\">Tipp 2: Verzichtet aufs Fliegen<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-3-w\u00e4hlt-eine-nachhaltige-unterkunft\" class=\"uagb-toc-link__trigger\">Tipp 3: W\u00e4hlt eine nachhaltige Unterkunft<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-4-packt-nachhaltig\" class=\"uagb-toc-link__trigger\">Tipp 4: Packt nachhaltig<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-5-nehmt-mehrwegverpackungen-mit\" class=\"uagb-toc-link__trigger\">Tipp 5: Nehmt Mehrwegverpackungen mit<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-6-esst-regional\" class=\"uagb-toc-link__trigger\">Tipp 6: Esst regional<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-7-unterst\u00fctzt-die-lokale-bev\u00f6lkerung\" class=\"uagb-toc-link__trigger\">Tipp 7: Unterst\u00fctzt die lokale Bev\u00f6lkerung<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-8-nehmt-r\u00fccksicht-auf-die-natur\" class=\"uagb-toc-link__trigger\">Tipp 8: Nehmt R\u00fccksicht auf die Natur<\/a><li class=\"uagb-toc__list\"><a href=\"#tipp-9-setzt-auf-nachhaltige-urlaubserinnerungen\" class=\"uagb-toc-link__trigger\">Tipp 9: Setzt auf nachhaltige Urlaubserinnerungen<\/a><li class=\"uagb-toc__list\"><a href=\"#adoptiert-einen-baum-mit-traum-ferienwohnungen\" class=\"uagb-toc-link__trigger\">Adoptiert einen Baum \u2013 mit Traum-Ferienwohnungen<\/a><li class=\"uagb-toc__list\"><a href=\"#die-9-tipps-auf-einen-blick\" class=\"uagb-toc-link__trigger\">Die 9 Tipps auf einen Blick<\/a><\/ol>\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-6820ef91\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-aa512a97\"><h2 class=\"uagb-heading-text\">Was ist \u00d6kotourismus \u00fcberhaupt?<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ihr habt mit Sicherheit schon einmal einen der folgenden Begriffe geh\u00f6rt: \u201eGr\u00fcner Urlaub\u201c, \u201enaturnaher Tourismus\u201c, \u201e\u00d6kotourismus\u201c oder auch \u201esanfter Tourismus\u201c. Diese Konzepte\u00a0 haben alle das gleiche Ziel, n\u00e4mlich <strong>der Natur m\u00f6glichst wenig zu schaden<\/strong>, w\u00e4hrend andererseits die Bev\u00f6lkerung der Urlaubsregion durch den <strong>Tourismus als verl\u00e4ssliche Einnahmequelle<\/strong> unterst\u00fctzt wird. Nachhaltig zu reisen ist wichtig f\u00fcr uns und vor allem unsere Nachkommen. Immer mehr Reisenden legen deshalb Wert darauf, ihren \u00f6kologischen Fu\u00dfabdruck w\u00e4hrend der Reise minimieren und ihre CO<sub>2<\/sub>-Emissionen auszugleichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Mit diesen 9 Tipps reist auch ihr ab sofort nachhaltiger.<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-c50949b5\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-255d0162\"><h2 class=\"uagb-heading-text\">Tipp 1: W\u00e4hlt ein Reiseziel in der N\u00e4he<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">M\u00f6chtet ihr mehr Nachhaltigkeit in eure Urlaubsgestaltung mit einbinden, beginnt dies bereits bei der Auswahl eures Reiseziels. Besonders wichtig ist hier die Entfernung zum Urlaubsziel: <strong>Je n\u00e4her das Urlaubsziel, desto klimafreundlicher<\/strong> ist auch die Anreise. Dabei sollte auch das Verh\u00e4ltnis zwischen der Reisedauer und der Entfernung zum Urlaubsort eine wichtige Rolle spielen. Nahhaltiger ist es, lieber einmal f\u00fcr l\u00e4nger in den Urlaub zu reisen, als mehrere kurze Trips zu unternehmen. Ihr k\u00f6nntet f\u00fcr die Fahrt zum Urlaubsort auch auf Mitfahrgelegenheiten oder Carsharing setzen. Am Urlaubsort selbst k\u00f6nnt ihr am besten <strong>\u00f6ffentliche Verkehrsmittel<\/strong> nutzen oder euch aufs Fahrrad schwingen, um Sehensw\u00fcrdigkeiten zu besuchen.\u00a0<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-d7821c45\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a74f1dff\"><h3 class=\"uagb-heading-text\">Die sch\u00f6nsten Regionen Deutschlands<\/h3><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Urlaub im eigenen Land liegt nicht nur voll im Trend, sondern ist auch sehr nachhaltig. Warum also in die Ferne schweifen, wenn <strong>auch Deutschland sch\u00f6ne Ecken hat<\/strong>! Die deutschen K\u00fcsten k\u00f6nnen durchaus mit denen am Mittelmeer mithalten. Wusstet ihr zum Beispiel, dass es auf <a href=\"https:\/\/www.traum-ferienwohnungen.de\/europa\/deutschland\/usedom\/ergebnisse\/\" target=\"_blank\" rel=\"noreferrer noopener\">Usedom<\/a> puderzuckerwei\u00dfe Str\u00e4nde gibt, die euch wie in der Karibik f\u00fchlen lassen? Und im S\u00fcden unseres Landes gibt es wundersch\u00f6ne Weinanbaugebiete, die denen in Frankreich oder Italien in nichts nachstehen.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auch f\u00fcr tiefblaues Wasser, atemberaubende Felsformationen oder imposante H\u00e4ngebr\u00fccken m\u00fcsst ihr nicht unbedingt eine stundenlange Flugreise auf euch nehmen. Denn all dies ist auch ebenfalls hier in Deutschland zu finden. Wir haben euch von einigen gro\u00dfartigen Reisezielen die deutschen Doppelg\u00e4nger herausgesucht, die euch mit Sicherheit begeistern werden.<\/p>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-block-53704a02\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-88d28d8d\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater\" href=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/deutsche-reiseziele-doppelgaenger\/\" rel=\"noopener noreferrer\" target=\"_blank\"><div class=\"uagb-button__link\">Jetzt Deutschlands Highlights entdecken<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-c752ba2d\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/bastei-bruecke-elbsandsteingebirge.jpg\" alt=\"Basteibr\u00fccke im Elbsandsteingebirge in der S\u00e4chsischen Schweiz\" data-id=\"30089\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/bastei-bruecke-elbsandsteingebirge.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/bastei-bruecke-elbsandsteingebirge\/\" class=\"wp-image-30089\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/bastei-bruecke-elbsandsteingebirge.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/bastei-bruecke-elbsandsteingebirge-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/seebruecke-selling-ruegen.jpg\" alt=\"Seebr\u00fccke Sellin und Strand auf R\u00fcgen\" data-id=\"30111\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/seebruecke-selling-ruegen.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/seebruecke-selling-ruegen\/\" class=\"wp-image-30111\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/seebruecke-selling-ruegen.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/seebruecke-selling-ruegen-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/eibsee-zugspitze.jpg\" alt=\"Blick auf den Eibsee mit Wald und der Zugspitze im Hintergrund\" data-id=\"30091\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/eibsee-zugspitze.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/eibsee-zugspitze\/\" class=\"wp-image-30091\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/eibsee-zugspitze.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/05\/eibsee-zugspitze-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-dec804be\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-08b733ff\"><h2 class=\"uagb-heading-text\">Tipp 2: Verzichtet aufs Fliegen<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Flugzeuge sind die gr\u00f6\u00dften Klimas\u00fcnder unter den Fortbewegungsmitteln! Im Vergleich zum Kurzstrecken-Flug ist ein vollbepacktes Auto in der Regel \u00f6kologischer. Wenn ihr auf den Flieger verzichtet, tragt ihr schon einen gro\u00dfen Teil zur Umweltschonung bei. Deutschland hat ganz wunderbare Reiseziele, die mit dem Auto oder dem Zug gut zu erreichen sind. Wollt oder k\u00f6nnt ihr nicht auf eine Flugreise verzichten, solltet ihr <strong>m\u00f6glichst lange vor Ort bleiben<\/strong> und \u2013 soweit m\u00f6glich \u2013 auf Direktfl\u00fcge setzen. Mittlerweile treiben auch immer mehr Fluggesellschaften mit <strong>umweltfreundlichen Konzepten f\u00fcr gr\u00fcnere Flugreisen<\/strong> den Nachhaltigkeitsgedanken voran. Dazu z\u00e4hlen zum Beispiel ein verringerter Treibstoffverbrauch, reduzierte L\u00e4rmbel\u00e4stigung sowie eine effizientere Auslastung der Flugzeuge. Dazu gibt es zahlreiche Organisationen, \u00fcber die ihr die CO<sub>2<\/sub>\u2013 Emissionen, die durch die Reise entstehen, kompensieren k\u00f6nnt. Anhand der Entfernung zwischen Wohnort und Reiseziel wird ein Betrag kalkuliert, mit dem anschlie\u00dfend <strong>Umweltprojekte weltweit unterst\u00fctzt <\/strong>werden. Eine richtig gute Sache!<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-046d518a\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-98ed4b8b\"><h2 class=\"uagb-heading-text\">Tipp 3: W\u00e4hlt eine nachhaltige Unterkunft<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Auch bei der Auswahl der Ferienunterkunft spielt f\u00fcr viele Urlauber ein bewusster und ethischer Lebensstil eine immer gr\u00f6\u00dfer werdende Rolle. Ferienwohnungen und Ferienh\u00e4user erm\u00f6glichen es euch besonders gut, auf Nachhaltigkeit im Urlaub zu achten. Denn gem\u00e4\u00df einer WWF-Studie sind <strong>Ferienwohnungen und -h\u00e4user im Vergleich zu einem Hotelaufenthalt pro Person gerechnet deutlich klimafreundlicher<\/strong>. Mittlerweile legen auch immer mehr Vermieter Wert auf ein nachhaltiges Angebot und es gibt zunehmend Ferienunterk\u00fcnfte, die mit einer nachhaltigen Ausstattung eingerichtet wurden oder sich durch weitere \u00f6kologische Standards auszeichnen. Woran ihr nachhaltige Ferienunterk\u00fcnfte erkennt, haben wir euch in einer kleinen Checkliste zusammengestellt.<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Nachhaltiger Energieverbrauch<\/strong>: Wird in der Ferienunterkunft \u00d6ko-Strom genutzt? Wird Energie wird auf erneuerbarem Weg, z.B. \u00fcber Solarpanels, generiert oder auf Energiesparbeleuchtung gesetzt?<\/li><li><strong>\u00d6kologische Einrichtung<\/strong>: Wurden nachwachsende Rohstoffe, wie z.B. Holz beim Bau der Unterkunft verwendet? Auch Minimalismus tr\u00e4gt zur Ressourcenschonung und Abfallvermeidung bei! Ein Tiny House beispielweise hinterl\u00e4sst aufgrund der minimalistischen Einrichtung und der geringeren Wohnfl\u00e4che einen deutlich geringeren \u00f6kologischen Fu\u00dfabdruck.<\/li><li><strong>Verpflegung<\/strong>: Werden lokale Anbieter mit einbezogen? Gibt es kleine Biol\u00e4den oder Hofl\u00e4den, die ihre Ware unverpackt, unbehandelt und mit kurzem Transportwegen anbieten?<\/li><li><strong>M\u00fcll-Management<\/strong>: Legt der Vermieter Wert auf M\u00fclltrennung? Weggeworfener M\u00fcll, L\u00e4rm- und Umweltbelastungen wirken sich negativ auf Tier- und Pflanzenwelt aus.<\/li><li><strong>Wasser-Management<\/strong>: Wird Regenwasser zur Garten- und Hausversorgung, wie z.B. f\u00fcr die, Waschmaschine oder Toilettensp\u00fclung wieder verwendet, um den Wasserverbrauch zu reduzieren?<\/li><li><strong>Nachhaltiger Nahverkehr<\/strong>: Kann man am Urlaubsort gut auf das Auto verzichten? Gibt es evtl. einen Fahrradverleih und ein gutes \u00d6PNV-Streckennetz?<\/li><\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">Bei uns findet ihr eine gro\u00dfe Auswahl an nachhaltig konzipierten Ferienunterk\u00fcnften und <a href=\"https:\/\/www.traum-ferienwohnungen.de\/europa\/deutschland\/ergebnisse\/?persons=1&amp;search=bio+bauernhof\" target=\"_blank\" rel=\"noreferrer noopener\">Bio-Bauernh\u00f6fen<\/a> f\u00fcr euren Urlaub. Wir stellen euch zwei Unterk\u00fcnfte vor, in denen ihr einen nachhaltigen Urlaub verbringen k\u00f6nnt!<\/p>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-0093afc5\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-5dce6ef6\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-cdb3b574\"><h3 class=\"uagb-heading-text\">Ferienhaus Fichtelgebirge<\/h3><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus-fichtelgebirge.jpg\" alt=\"\" data-id=\"45227\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus-fichtelgebirge.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?attachment_id=45227\" class=\"wp-image-45227\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus-fichtelgebirge.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus-fichtelgebirge-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses nachhaltige und in jeder Hinsicht umweltbewusst gebaute Holzhaus empf\u00e4ngt euch mit viel Gem\u00fctlichkeit. Es wurde komplett mit <strong>Holz aus den heimischen W\u00e4ldern<\/strong> des Fichtelgebirges gebaut und die Zirbenholz- und Lehmw\u00e4nde sorgen f\u00fcr ein gesundes Wohnklima und einen erholsamen Schlaf. F\u00fcr eine gem\u00fctliche Atmosph\u00e4re sorgen das Eichenparkett und ein Pelletofen. Holz-Alu-Fenster und Dreifachverglasung mit Raffstore stehen ebenfalls f\u00fcr das konsequent \u00f6kologisch ausgerichtete Gesamtkonzept. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Auf einer Wohnfl\u00e4che von 59 m<sup>2 <\/sup>und einer zus\u00e4tzlichen 25m<sup>2<\/sup> gro\u00dfen Sonnenterrasse k\u00f6nnt ihr es euch in eurem Urlaub so richtig gut gehen lassen. Die Lage mitten in der Natur bietet euch eine sch\u00f6ne Aussicht ins Gr\u00fcne und l\u00e4dt zum Entschleunigen ein. Auch die Umgebung des Ferienhauses wird der Nachhaltigkeitsgedanke sichtbar: Vor dem Haus sind <strong>Hochbeete mit verschiedenem Gem\u00fcse und Kr\u00e4utern <\/strong>angelegt, die Selbstversorgung aus dem eigenen Gem\u00fcsegarten und somit nachhaltigen Konsum von Lebensmitteln erm\u00f6glichen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Das Ferienhaus ist barrierefrei und somit auch f\u00fcr Menschen mit eingeschr\u00e4nkter Mobilit\u00e4t zu empfehlen! Mit einem Aufenthalt in dieser Ferienunterkunft k\u00f6nnt ihr euren \u00f6kologischen Fu\u00dfabdruck reduzieren!<\/p>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-block-32a54c06\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-5209ad05\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater\" href=\"https:\/\/www.traum-ferienwohnungen.de\/334950\/\" rel=\"noopener noreferrer\" target=\"_blank\"><div class=\"uagb-button__link\">Zum Ferienhaus Fichtelgebirge<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-9a4846ad\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-8af0bb10\"><h3 class=\"uagb-heading-text\">Ferienhaus Korn<\/h3><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-3 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus_korn.jpg\" alt=\"\" data-id=\"45226\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus_korn.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?attachment_id=45226\" class=\"wp-image-45226\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus_korn.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/ferienhaus_korn-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Dieses reetgedeckte historische Fachwerkh\u00e4uschen im Ostseebad Prerow wurde<strong> im Jahr 2019 voll\u00f6kologisch und aufwendig saniert<\/strong>. Hier wurde auch gro\u00dfen Wert auf eine gr\u00f6\u00dftenteils nachhaltige Ausstattung gelegt. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Die Lage ist richtig von gr\u00fcner Natur gepr\u00e4gt, denn das Ferienhaus befindet sich direkt am Rande des Nationalparks Vorpommersche Bodenlandschaft \u2013 dem gr\u00f6\u00dften Nationalpark an der deutschen Ostseek\u00fcste. Die wundersch\u00f6ne, gesch\u00fctzte Umgebung <strong>l\u00e4sst vor allem Naturfans so richtig aufatmen<\/strong>! Die nahegelegenen Str\u00e4nde sind vom Ferienhaus aus gut zu erreichen und versprechen Badespa\u00df und lange Strandspazierg\u00e4nge. Eine perfekte und gleichzeitig auch nachhaltige M\u00f6glichkeit den Urlaubsort zu erkunden, ist sich ein Leihfahrrad zu schnappen, eine der sch\u00f6nen Routen auszuw\u00e4hlen und sich den Ostseewind um die Nase wehen zu lassen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Und wenn es doch mal etwas k\u00fchler ist, l\u00e4dt ein Kamin zu ein paar gem\u00fctlichen Stunden bei leckeren Hei\u00dfgetr\u00e4nken ein.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Egal ob Sommer oder Winter: Hier k\u00f6nnt ihr einen entspannten Urlaub verbringen, der dazu noch die Umwelt entlastet.<\/p>\n\n\n\n<div class=\"wp-block-uagb-buttons uagb-buttons__outer-wrap uagb-block-3ac50001\"><div class=\"uagb-buttons__wrap uagb-buttons-layout-wrap\">\n<div class=\"wp-block-uagb-buttons-child uagb-buttons__outer-wrap uagb-block-1672295b\"><div class=\"uagb-button__wrapper\"><a class=\"uagb-buttons-repeater\" href=\"https:\/\/www.traum-ferienwohnungen.de\/314714\/\" rel=\"noopener noreferrer\" target=\"_blank\"><div class=\"uagb-button__link\">Zum Ferienhaus Korn<\/div><\/a><\/div><\/div>\n<\/div><\/div>\n<\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-4af0e2f5\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-f4349afb\"><h2 class=\"uagb-heading-text\">Tipp 4: Packt nachhaltig<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nachhaltigkeit beginnt schon beim Packen des Reisegep\u00e4cks. Hier gilt das Motto <strong>\u201eWeniger ist mehr\u201c<\/strong>. Packt bitte nur so viel ein, wie ihr auch wirklich braucht. Denn egal welches Reisemittel ihr w\u00e4hlt: Je mehr Gewicht das Gep\u00e4ck hat, desto mehr Benzin und Energie wird verbraucht und umso mehr CO2 produziert!<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">F\u00fcr Shampoo, Duschgel &amp; Co. k\u00f6nnt ihr euch ein Set an <strong>kleinen wiederverwendbaren Flaschen kaufen<\/strong> und euch etwas von eurem Shampoo und Duschgel f\u00fcr die Reise abf\u00fcllen. Diese Fl\u00e4schchen lassen sich dann f\u00fcr jeden Urlaub wieder verwenden und es wird an Verpackungsm\u00fcll gespart. Unser Tipp: Ihr k\u00f6nnt daf\u00fcr auch perfekt leere Cremedosen oder kleine Schraubgl\u00e4ser aus dem K\u00fcchenbereich nutzen. <\/p>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-a7964c87\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-1\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-41477d55\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<p class=\"wp-block-paragraph\"><strong>Unser Tipp:<\/strong> Ihr k\u00f6nnt daf\u00fcr auch perfekt leere Cremedosen oder kleine Schraubgl\u00e4ser aus dem K\u00fcchenbereich nutzen. Wer ganz auf Plastikverpackungen verzichten m\u00f6chte, setzt am besten von vornherein auf <strong>festes Shampoo und Seife<\/strong>.<\/p>\n<\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-9cdff554\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-13cc1923\"><h2 class=\"uagb-heading-text\">Tipp 5: Nehmt Mehrwegverpackungen mit<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<section class=\"wp-block-uagb-columns uagb-columns__wrap uagb-columns__background-undefined uagb-columns__stack-mobile uagb-columns__valign-undefined uagb-columns__gap-10 alignundefined uagb-block-443fb006\"><div class=\"uagb-columns__overlay\"><\/div><div class=\"uagb-columns__inner-wrap uagb-columns__columns-2\">\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-ce04e209\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<p class=\"wp-block-paragraph\">Vor allem, wer im Urlaub viel unterwegs ist und hier und da einen kleinen Snack oder ein Getr\u00e4nk zu sich nimmt, verursacht \u2013 h\u00e4ufig ganz unbewusst \u2013 jede Menge M\u00fcll. Mittlerweile gibt es zahlreiche <strong>nachhaltige Alternativen zu Plastikartikeln<\/strong>. Hier ein paar Tipps, mit denen sich genau dieser unn\u00f6tige M\u00fcll clever aus dem Urlaubsalltag verbannen l\u00e4sst:<\/p>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>Jutebeutel <\/strong>statt Plastikt\u00fcte. Klein und zusammengepackt passt er in jeden Koffer<\/li><li><strong>wiederverwendbare Wasserflasche<\/strong> mit Filter \u2013 kann nach Belieben nachgef\u00fcllt werden<\/li><li>den eigenen <strong>wiederverwendbaren Coffee-To-Go-Becher<\/strong> \u2013 f\u00fcr den Kaffee f\u00fcr unterwegs<\/li><li><strong>wiederverwendbare Beh\u00e4lter und Dosen <\/strong>\u2013 f\u00fcr den Snack unterwegs<\/li><li><strong>Stoffservietten<\/strong> oder Geschirrhandt\u00fccher \u2013 zum Abwischen, Putzen und Einwickeln<\/li><li><strong>Besteck<\/strong> \u2013 L\u00f6ffel, Gabel, Messer oder die platzsparenden Varianten \u201eSpork\u201c und \u201eG\u00f6ffel\u201c<\/li><\/ul>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-uagb-column uagb-column__wrap uagb-column__background-undefined uagb-block-f93fb230\"><div class=\"uagb-column__overlay\"><\/div><div class=\"uagb-column__inner-wrap\">\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-4 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><a href=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen-packen\/\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-packen.jpg\" alt=\"Nachhaltiges Reisen Packen\" data-id=\"28028\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-packen.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen-packen\/\" class=\"wp-image-28028\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-packen.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-packen-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/a><\/figure><\/li><\/ul><\/figure>\n<\/div><\/div>\n<\/div><\/section>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-896fa14d\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-7c6258fd\"><h2 class=\"uagb-heading-text\">Tipp 6: Esst regional<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Die typischen Speisen und Getr\u00e4nke der Urlaubsregion zu genie\u00dfen, geh\u00f6rt doch einfach in jedem Urlaub dazu. Perfekt also, dass ihr mit dem Verzehr von regionalem Essen dazu beitragen k\u00f6nnt, der Umwelt etwas Gutes zu tun! Denn je <strong>k\u00fcrzer die Transportwege <\/strong>des jeweiligen Lebensmittels sind, desto mehr wird die Umwelt entlastet. Anstatt auf einen Snack in ein Fast-Food-Restaurant einzukehren, besucht lieber das kleine Restaurant um die Ecke, das euch mit regionalen Spezialit\u00e4ten verw\u00f6hnt. Das ist nicht nur viel umweltschonender, sondern meistens auch die gem\u00fctlichere, ges\u00fcndere und leckerere Variante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Achtet am besten auch auf <strong>saisonale Lebensmittel<\/strong>, denn da diese nicht energieintensiv gelagert werden m\u00fcssen oder auf langen Transportwegen ins Land kommen, entlasten sie ebenfalls die Umwelt.<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-57b479c0\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-a030fba7\"><h2 class=\"uagb-heading-text\">Tipp 7: Unterst\u00fctzt die lokale Bev\u00f6lkerung<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Nachhaltiges Reisen hat vor allem zum Ziel, der Natur m\u00f6glichst wenig zu schaden. Doch auch wirtschaftlich gesehen gibt es M\u00f6glichkeiten, mehr Nachhaltigkeit in euren Urlaub zu integrieren. Viele Reiseziele leben vom Tourismus, doch oft sind es vor allem gro\u00dfe Hotelketten, die hiervon profitieren. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Wenn ihr die Menschen und die Natur am Urlaubsort nachhaltig f\u00f6rdern m\u00f6chtet, k\u00f6nnt ihr darauf achten m\u00f6glichst oft die lokale Bev\u00f6lkerung zu unterst\u00fctzen. Dazu z\u00e4hlt z.B., eine Ferienunterkunft <strong>direkt bei einem lokalen Gastgeber zu buchen<\/strong>, <strong>lokale Restaurants<\/strong> zu besuchen und in den kleinen <strong>Gesch\u00e4ften und auf M\u00e4rkten vor Ort<\/strong> einzukaufen. Au\u00dferdem gibt es bereits verschiedene Tourismusvereine, die sich f\u00fcr die Bev\u00f6lkerung am Urlaubsort einsetzen und diese aktiv in ihre Unternehmensphilosophie einbeziehen. Es lohnt sich also schon bei der Reiseplanung hierauf zu achten!<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-ad78577f\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<figure class=\"wp-block-gallery columns-3 is-cropped wp-block-gallery-5 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionaler-markt.jpg\" alt=\"\" data-id=\"45257\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionaler-markt.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?attachment_id=45257\" class=\"wp-image-45257\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionaler-markt.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionaler-markt-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionales-essen-geniessen-urlaub.jpg\" alt=\"\" data-id=\"45258\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionales-essen-geniessen-urlaub.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?attachment_id=45258\" class=\"wp-image-45258\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionales-essen-geniessen-urlaub.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/regionales-essen-geniessen-urlaub-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure><\/li><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"400\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-huehner.jpg\" alt=\"Nachhaltiges Reisen H\u00fchner\" data-id=\"28026\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-huehner.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen-huehner\/\" class=\"wp-image-28026\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-huehner.jpg 600w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/01\/nachhaltiges-reisen-huehner-300x200.jpg 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><figcaption class=\"blocks-gallery-item__caption\">Nachhaltiges Reisen H\u00fchner<\/figcaption><\/figure><\/li><\/ul><\/figure>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-c838b9d5\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-12f80ec3\"><h2 class=\"uagb-heading-text\">Tipp 8: Nehmt R\u00fccksicht auf die Natur<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Wer umweltfreundlich reisen m\u00f6chte, sollte m\u00f6glichst schonend mit der Umwelt umgehen. Bitte achtet darauf, dass ihr<strong> euren M\u00fcll wieder mitnehmt<\/strong> und euch in den Naturschutzgebieten<strong> an die vorgeschriebenen Wege haltet<\/strong>, um nicht unn\u00f6tig in die Lebensr\u00e4ume der Tiere und Pflanzen einzudringen. Gerade im Fr\u00fchjahr und Sommer nisten in vielen Naturschutzgebieten teils seltene V\u00f6gel, und viele Tiere haben Jungtiere, die besser nicht gest\u00f6rt werden sollten.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Grillen solltet ihr nur an den daf\u00fcr ausgewiesenen Pl\u00e4tzen.<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-95cddc3c\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-063b60a1\"><h2 class=\"uagb-heading-text\">Tipp 9: Setzt auf nachhaltige Urlaubserinnerungen<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Ein Fotobuch ist immer eine tolle Erinnerung an die sch\u00f6nste Zeit des Jahres. Auch hier k\u00f6nnt ihr zur Nachhaltigkeit beitragen. Achtet auf Anbieter, die <strong>FSC-zertifiziertes Papier<\/strong> verwenden. FSC steht f\u00fcr \u201eForest Stewardship Council\u201c und ist eine internationale Zertifizierung f\u00fcr nachhaltige Waldwirtschaft. Viele Anbieter von Fotob\u00fcchern nutzen bereits hochwertiges Naturpapier, umweltschonende Materialen und eine klimaneutrale Herstellung. Wer g\u00e4nzlich auf Papier verzichten m\u00f6chte, kann auch ein <strong>digitales Fotoalbum erstellen<\/strong> oder die Urlaubserinnerungen in einem Video zusammenf\u00fcgen und in einer Cloud abspeichern. So k\u00f6nnt ihr euch die Urlaubsstimmung jederzeit wieder zur\u00fcck in den Alltag holen!<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-d51b375b\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3a809e62\"><h2 class=\"uagb-heading-text\">Adoptiert einen Baum \u2013 mit Traum-Ferienwohnungen<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">\u00dcbrigens: Bei jeder Buchung einer Ferienunterkunft k\u00f6nnt ihr jetzt ganz einfach dazu beitragen, euren \u00f6kologischen Fu\u00dfabdruck zu reduzieren. In<strong> einer gemeinsamen Mission mit der Life Terra Foundation<\/strong> pflanzen wir f\u00fcr jede Buchung, die \u00fcber unser Portal erfolgt, einen neuen Baum, den ihr dann adoptieren und zu eurem Baum machen k\u00f6nnt! <a href=\"https:\/\/unternehmen.traum-ferienwohnungen.de\/presse\/pressemitteilungen\/traum-ferienwohnungen-ermoglicht-urlaubern-baumpatenschaften\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mehr Informationen zum Life Terra Projekt findet ihr auch hier<\/a>.<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 wp-block-gallery-6 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"66\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra-300x66.png\" alt=\"\" data-id=\"45241\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra.png\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?attachment_id=45241\" class=\"wp-image-45241\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra-300x66.png 300w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra-1024x225.png 1024w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra-768x168.png 768w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra-1536x337.png 1536w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/logo-life-terra-2048x449.png 2048w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure><\/li><\/ul><\/figure>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-a1f92d3d\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\">\n<div class=\"wp-block-uagb-advanced-heading uagb-block-3f953f32\"><h2 class=\"uagb-heading-text\">Die 9 Tipps auf einen Blick<\/h2><div class=\"uagb-separator-wrap\"><div class=\"uagb-separator\"><\/div><\/div><p class=\"uagb-desc-text\"><\/p><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">Hier seht ihr noch einmal unsere 9 einfachen Tipps f\u00fcr mehr \u00d6kotourismus auf einen Blick! Lasst uns gemeinsam dazu beitragen unseren Planeten Erde durch nachhaltiges Reisen zu sch\u00fctzen! Denn echte Ver\u00e4nderung kann nur eintreten, wenn alle mitmachen. Wir sind auf jeden Fall bereit f\u00fcr die Mission \u201eGr\u00fcnes Reisen\u201c!<\/p>\n\n\n\n<figure class=\"wp-block-gallery columns-1 is-cropped wp-block-gallery-7 is-layout-flex wp-block-gallery-is-layout-flex\"><ul class=\"blocks-gallery-grid\"><li class=\"blocks-gallery-item\"><figure><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"500\" src=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/nachhaltig-reisen-tipps-grafik.jpg\" alt=\"\" data-id=\"45239\" data-full-url=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/nachhaltig-reisen-tipps-grafik.jpg\" data-link=\"https:\/\/www.traum-ferienwohnungen.de\/urlaubsmagazin\/?attachment_id=45239\" class=\"wp-image-45239\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/nachhaltig-reisen-tipps-grafik.jpg 800w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/nachhaltig-reisen-tipps-grafik-300x188.jpg 300w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2019\/05\/nachhaltig-reisen-tipps-grafik-768x480.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/><\/figure><\/li><\/ul><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Habt ihr noch weitere Tipps und Tricks, wie ihr eure Reisen nachhaltiger gestalten k\u00f6nnt? Wir freuen uns \u00fcber eure Anregungen in den Kommentaren!<\/p>\n<\/div><\/section>\n\n\n\n<section class=\"wp-block-uagb-section uagb-section__wrap uagb-section__background-undefined uagb-block-fc415696\"><div class=\"uagb-section__overlay\"><\/div><div class=\"uagb-section__inner-wrap\"><h4 class=\"style-h2\">Diese Themen k\u00f6nnten dich auch interessieren:<\/h4><div  class=\"tfw-related-articles-wrap\"><div class=\"tfw-card all-post tfw-purple\">\n\t\t\t\t<div class=\"cat-list\"> <a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/allgemein\/\" class=\"cat-item\">Allgemein<\/a><a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/reisefuehrer\/\" class=\"cat-item\">Reisef\u00fchrer<\/a><a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/reisewissen\/\" class=\"cat-item\">Reisewissen<\/a> <\/div>\n\t\t\t\t<h3>Comer See Urlaub: Top-Sehensw\u00fcrdigkeiten &#038; Reisetipps<\/h3>\n\t\t\t\t<a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/urlaub-am-comer-see\/\" rel=\"bookmark\">\n\t\t\t\t\t<figure class=\"post-image post-image--desktop\"> \n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"500\" src=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2026\/03\/Main-Banner-lake-como.png\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2026\/03\/Main-Banner-lake-como.png 1200w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2026\/03\/Main-Banner-lake-como-300x125.png 300w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2026\/03\/Main-Banner-lake-como-1024x427.png 1024w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2026\/03\/Main-Banner-lake-como-768x320.png 768w\" sizes=\"(max-width: 1200px) 100vw, 1200px\" \/>\n\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t<figure class=\"post-image post-image--mobile\"> \n\t\t\t\t\t\t<img decoding=\"async\" src=\" https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2026\/03\/Main-Banner-lake-como.png \" \/>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/a>\n\t\t\t\t<p>Wenn steile, gr\u00fcne Berge direkt in tiefblaues Wasser fallen und pr\u00e4chtige, alte Villen die Ufer s\u00e4umen, seid ihr an einem der sch\u00f6nsten Orte Europas angekommen. Der drittgr\u00f6\u00dfte See Italiens verzaubert Besucher aus aller Welt mit seiner einzigartigen Magie.\r\nOb idyllische kleine D\u00f6rfer mit bunten H\u00e4usern, atemberaubende botanische G\u00e4rten oder entspannte Fahrten mit dem Boot- wir zeigen euch die absoluten Highlights. Entdeckt mit uns die besten Orte f\u00fcr eure n\u00e4chste unvergessliche Reise in den sonnigen S\u00fcden.\r\n\n\t\t\t\t<\/p>\n\t\t\t\t<a class=\"tfw-button tfw-button--black\" href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/urlaub-am-comer-see\/\" rel=\"bookmark\"> Mehr erfahren<\/a>\n\t\t\t<\/div><div class=\"tfw-card all-post tfw-blue\">\n\t\t\t\t<div class=\"cat-list\"> <a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/inspiration\/\" class=\"cat-item\">Inspiration<\/a><a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/reisewissen\/\" class=\"cat-item\">Reisewissen<\/a> <\/div>\n\t\t\t\t<h3>Skigebiete Bayern: Euer Winterparadies f\u00fcr den Skiurlaub<\/h3>\n\t\t\t\t<a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/skigebiete-bayern\/\" rel=\"bookmark\">\n\t\t\t\t\t<figure class=\"post-image post-image--desktop\"> \n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2400\" height=\"550\" src=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Skifahrer in Bayern mit Bergpanorama\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2.jpg 2400w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2-300x69.jpg 300w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2-1024x235.jpg 1024w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2-768x176.jpg 768w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2-1536x352.jpg 1536w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-2-2048x469.jpg 2048w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" \/>\n\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t<figure class=\"post-image post-image--mobile\"> \n\t\t\t\t\t\t<img decoding=\"async\" src=\" https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/mobile-featured-img-3.jpg \" \/>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/a>\n\t\t\t\t<p>Plant euren Skiurlaub in der N\u00e4he der besten Skigebiete Bayerns. Wir zeigen euch die f\u00fcnf sch\u00f6nsten Skigebiete in dem Bundesland.Zudem haben wir wichtige Tipps zusammengestellt, damit euer Urlaub unvergesslich wird.\n\t\t\t\t<\/p>\n\t\t\t\t<a class=\"tfw-button tfw-button--black\" href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/skigebiete-bayern\/\" rel=\"bookmark\"> Mehr erfahren<\/a>\n\t\t\t<\/div><div class=\"tfw-card all-post tfw-blue\">\n\t\t\t\t<div class=\"cat-list\"> <a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/inspiration\/\" class=\"cat-item\">Inspiration<\/a><a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/reisewissen\/\" class=\"cat-item\">Reisewissen<\/a> <\/div>\n\t\t\t\t<h3>Wo ist es im Januar warm in Europa<\/h3>\n\t\t\t\t<a href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wo-ist-es-im-januar-warm-europa\/\" rel=\"bookmark\">\n\t\t\t\t\t<figure class=\"post-image post-image--desktop\"> \n\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"2400\" height=\"550\" src=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"Strand von Cofete auf Fuerteventura\" srcset=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1.jpg 2400w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1-300x69.jpg 300w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1-1024x235.jpg 1024w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1-768x176.jpg 768w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1-1536x352.jpg 1536w, https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/feature-img-for-traum-1-2048x469.jpg 2048w\" sizes=\"(max-width: 2400px) 100vw, 2400px\" \/>\n\t\t\t\t\t<\/figure>\n\n\t\t\t\t\t<figure class=\"post-image post-image--mobile\"> \n\t\t\t\t\t\t<img decoding=\"async\" src=\" https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2023\/11\/mobile-featured-img-1.jpg \" \/>\n\t\t\t\t\t<\/figure>\n\t\t\t\t<\/a>\n\t\t\t\t<p>Europa eignet sich im Januar nicht nur zum Skifahren, sondern kann euch auch zahlreiche warme Reiseziele bieten.Wir zeigen euch, wo es im Januar in Europa warm ist und welche Regionen sich f\u00fcr euren Urlaub eignen.\n\t\t\t\t<\/p>\n\t\t\t\t<a class=\"tfw-button tfw-button--black\" href=\"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wo-ist-es-im-januar-warm-europa\/\" rel=\"bookmark\"> Mehr erfahren<\/a>\n\t\t\t<\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":16,"featured_media":29954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_crdt_document":"","_uag_custom_page_level_css":"","footnotes":""},"categories":[12],"tags":[23,30,24],"class_list":["post-29299","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reisewissen","tag-familienurlaub","tag-ratgeber","tag-urlaub-zu-zweit"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nachhaltig Reisen - 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus<\/title>\n<meta name=\"description\" content=\"Nachhaltiges Reisen: Vom Packen bis zum Sightseeing, wir zeigen wie du im Urlaub auf die Umwelt achten und trotzdem einen super Urlaub haben kannst.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nachhaltig Reisen - 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus\" \/>\n<meta property=\"og:description\" content=\"Nachhaltiges Reisen: Vom Packen bis zum Sightseeing, wir zeigen wie du im Urlaub auf die Umwelt achten und trotzdem einen super Urlaub haben kannst.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/\" \/>\n<meta property=\"og:site_name\" content=\"Urlaubsmagazin - Traum Ferienwohnungen\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-22T05:11:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-04-22T05:11:22+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2400\" \/>\n\t<meta property=\"og:image:height\" content=\"550\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Redaktion\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"12\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/\"},\"author\":{\"name\":\"Redaktion\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/#\\\/schema\\\/person\\\/7b4cb40c5cd96f13124149de2dd4417d\"},\"headline\":\"Nachhaltig Reisen &#8211; 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus\",\"datePublished\":\"2022-04-22T05:11:20+00:00\",\"dateModified\":\"2022-04-22T05:11:22+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/\"},\"wordCount\":2287,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.traumhomes.nl\\\/urlaubsmagazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/umweltfreundlich-reisen-header-desktop.jpg\",\"keywords\":[\"Familienurlaub\",\"Ratgeber\",\"Urlaub zu zweit\"],\"articleSection\":[\"Reisewissen\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/\",\"url\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/\",\"name\":\"Nachhaltig Reisen - 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.traumhomes.nl\\\/urlaubsmagazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/umweltfreundlich-reisen-header-desktop.jpg\",\"datePublished\":\"2022-04-22T05:11:20+00:00\",\"dateModified\":\"2022-04-22T05:11:22+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/#\\\/schema\\\/person\\\/7b4cb40c5cd96f13124149de2dd4417d\"},\"description\":\"Nachhaltiges Reisen: Vom Packen bis zum Sightseeing, wir zeigen wie du im Urlaub auf die Umwelt achten und trotzdem einen super Urlaub haben kannst.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.traumhomes.nl\\\/urlaubsmagazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/umweltfreundlich-reisen-header-desktop.jpg\",\"contentUrl\":\"https:\\\/\\\/www.traumhomes.nl\\\/urlaubsmagazin\\\/wp-content\\\/uploads\\\/2021\\\/04\\\/umweltfreundlich-reisen-header-desktop.jpg\",\"width\":2400,\"height\":550,\"caption\":\"Zwei junge Frauen wandern durch Naturlandschaften \u2013 Umweltfreundlich reisen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/nachhaltiges-reisen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/urlaubsmagazin.svc.tfw.io\\\/urlaubsmagazin\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nachhaltig Reisen &#8211; 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/#website\",\"url\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/\",\"name\":\"Urlaubsmagazin - Traum Ferienwohnungen\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/urlaubsmagazin.traum-ferienwohnungen.de\\\/urlaubsmagazin\\\/#\\\/schema\\\/person\\\/7b4cb40c5cd96f13124149de2dd4417d\",\"name\":\"Redaktion\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7f03b35327db633c7cb65950765e5e170c5066dfa9ccd2f2b176bcf0dbc3f99?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7f03b35327db633c7cb65950765e5e170c5066dfa9ccd2f2b176bcf0dbc3f99?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e7f03b35327db633c7cb65950765e5e170c5066dfa9ccd2f2b176bcf0dbc3f99?s=96&d=mm&r=g\",\"caption\":\"Redaktion\"},\"url\":\"https:\\\/\\\/www.traumhomes.nl\\\/urlaubsmagazin\\\/author\\\/redaktion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nachhaltig Reisen - 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus","description":"Nachhaltiges Reisen: Vom Packen bis zum Sightseeing, wir zeigen wie du im Urlaub auf die Umwelt achten und trotzdem einen super Urlaub haben kannst.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/","og_locale":"de_DE","og_type":"article","og_title":"Nachhaltig Reisen - 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus","og_description":"Nachhaltiges Reisen: Vom Packen bis zum Sightseeing, wir zeigen wie du im Urlaub auf die Umwelt achten und trotzdem einen super Urlaub haben kannst.","og_url":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/","og_site_name":"Urlaubsmagazin - Traum Ferienwohnungen","article_published_time":"2022-04-22T05:11:20+00:00","article_modified_time":"2022-04-22T05:11:22+00:00","og_image":[{"width":2400,"height":550,"url":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg","type":"image\/jpeg"}],"author":"Redaktion","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"Redaktion","Gesch\u00e4tzte Lesezeit":"12\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#article","isPartOf":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/"},"author":{"name":"Redaktion","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/#\/schema\/person\/7b4cb40c5cd96f13124149de2dd4417d"},"headline":"Nachhaltig Reisen &#8211; 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus","datePublished":"2022-04-22T05:11:20+00:00","dateModified":"2022-04-22T05:11:22+00:00","mainEntityOfPage":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/"},"wordCount":2287,"commentCount":0,"image":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg","keywords":["Familienurlaub","Ratgeber","Urlaub zu zweit"],"articleSection":["Reisewissen"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/","url":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/","name":"Nachhaltig Reisen - 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus","isPartOf":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/#website"},"primaryImageOfPage":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#primaryimage"},"image":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg","datePublished":"2022-04-22T05:11:20+00:00","dateModified":"2022-04-22T05:11:22+00:00","author":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/#\/schema\/person\/7b4cb40c5cd96f13124149de2dd4417d"},"description":"Nachhaltiges Reisen: Vom Packen bis zum Sightseeing, wir zeigen wie du im Urlaub auf die Umwelt achten und trotzdem einen super Urlaub haben kannst.","breadcrumb":{"@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#primaryimage","url":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg","contentUrl":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg","width":2400,"height":550,"caption":"Zwei junge Frauen wandern durch Naturlandschaften \u2013 Umweltfreundlich reisen"},{"@type":"BreadcrumbList","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/nachhaltiges-reisen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/urlaubsmagazin.svc.tfw.io\/urlaubsmagazin\/"},{"@type":"ListItem","position":2,"name":"Nachhaltig Reisen &#8211; 9 einfache Tipps f\u00fcr mehr \u00d6kotourismus"}]},{"@type":"WebSite","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/#website","url":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/","name":"Urlaubsmagazin - Traum Ferienwohnungen","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/urlaubsmagazin.traum-ferienwohnungen.de\/urlaubsmagazin\/#\/schema\/person\/7b4cb40c5cd96f13124149de2dd4417d","name":"Redaktion","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/e7f03b35327db633c7cb65950765e5e170c5066dfa9ccd2f2b176bcf0dbc3f99?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e7f03b35327db633c7cb65950765e5e170c5066dfa9ccd2f2b176bcf0dbc3f99?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e7f03b35327db633c7cb65950765e5e170c5066dfa9ccd2f2b176bcf0dbc3f99?s=96&d=mm&r=g","caption":"Redaktion"},"url":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/author\/redaktion\/"}]}},"uagb_featured_image_src":{"full":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop.jpg",2400,550,false],"thumbnail":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop-150x150.jpg",150,150,true],"medium":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop-300x69.jpg",300,69,true],"medium_large":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop-768x176.jpg",768,176,true],"large":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop-1024x235.jpg",1024,235,true],"1536x1536":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop-1536x352.jpg",1536,352,true],"2048x2048":["https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-content\/uploads\/2021\/04\/umweltfreundlich-reisen-header-desktop-2048x469.jpg",2048,469,true]},"uagb_author_info":{"display_name":"Redaktion","author_link":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/author\/redaktion\/"},"uagb_comment_info":14,"uagb_excerpt":null,"_links":{"self":[{"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/posts\/29299","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/users\/16"}],"replies":[{"embeddable":true,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/comments?post=29299"}],"version-history":[{"count":5,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/posts\/29299\/revisions"}],"predecessor-version":[{"id":56163,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/posts\/29299\/revisions\/56163"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/media\/29954"}],"wp:attachment":[{"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/media?parent=29299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/categories?post=29299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.traumhomes.nl\/urlaubsmagazin\/wp-json\/wp\/v2\/tags?post=29299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}